{"id":198230,"date":"2025-06-19T08:32:50","date_gmt":"2025-06-19T08:32:50","guid":{"rendered":"https:\/\/floridahomeshares.com\/?post_type=listing&#038;p=198230"},"modified":"2026-07-14T20:43:28","modified_gmt":"2026-07-14T20:43:28","slug":"epic-luxury-theme-home-w-private-pool-game-room","status":"publish","type":"listing","link":"https:\/\/floridahomeshares.com\/fr\/listing\/epic-luxury-theme-home-w-private-pool-game-room\/","title":{"rendered":"Piscine d&#039;eau sal\u00e9e chauff\u00e9e avec salle de jeux et de cin\u00e9ma"},"content":{"rendered":"<p>Plongez dans un monde d&#039;imagination pure dans cette retraite \u00e9pique sur le th\u00e8me du multivers, \u00e0 quelques minutes d&#039;Orlando ! Avec des th\u00e8mes comme Harry Potter, Game of Thrones, Star Wars, Black Panther, Avengers et Avatar, chaque pi\u00e8ce est un portail vers un nouvel univers. La maison a tout ce qu&#039;il vous faut : piscine d&#039;eau sal\u00e9e chauff\u00e9e, jacuzzi, salle de cin\u00e9ma, salle de jeux Game of Thrones, cuisine enti\u00e8rement \u00e9quip\u00e9e, fumoir barbecue, fauteuil de massage, consoles de jeux, ping-pong et billard. R\u00e9servez votre escapade multivers d\u00e8s maintenant !<\/p>\n<p>\u2605\u2605 CHAMBRES \u2605\u2605<br \/>\nCette maison \u00e0 deux \u00e9tages comprend trois belles chambres et peut accueillir confortablement jusqu&#039;\u00e0 9 personnes. Deux chambres se trouvent \u00e0 l&#039;\u00e9tage et une chambre avec canap\u00e9-lit au rez-de-chauss\u00e9e. Toutes sont \u00e9quip\u00e9es de matelas confortables, de linge de maison et de grandes fen\u00eatres laissant entrer une belle lumi\u00e8re naturelle.<\/p>\n<p>\u2739Deux chambres principales\u00a0: lit king-size, t\u00e9l\u00e9vision \u00e0 \u00e9cran plat et salle de bains privative. L&#039;une des chambres principales est situ\u00e9e au rez-de-chauss\u00e9e et l&#039;autre au deuxi\u00e8me \u00e9tage.<br \/>\n\u2739Chambre 3 : lits superpos\u00e9s avec un lit gigogne simple, TV \u00e9cran plat, acc\u00e8s salle de bain partag\u00e9e<\/p>\n<p>\u2714 Canap\u00e9-lit deux places dans le grand salon<\/p>\n<p>\u2605\u2605 SALLES DE BAINS \u2605\u2605<\/p>\n<p>\u2739Salle de bain 1 : Salle de bain priv\u00e9e compl\u00e8te avec douche et double vasque.<br \/>\n\u2739Salle de bain 2 : Salle de bain priv\u00e9e compl\u00e8te avec douche, baignoire de jardin et un lavabo.<br \/>\n\u2739Salle de bain 3 : Salle de bain compl\u00e8te avec baignoire et douche combin\u00e9es.<br \/>\n\u2739Salle de bain 4 : Demi-salle de bain au premier \u00e9tage.<\/p>\n<p>\u2714 Articles de toilette essentiels fournis (y compris shampoing, gel douche et revitalisant)<br \/>\n\u2714 S\u00e8che-cheveux<br \/>\n\u2714 Serviettes fra\u00eeches<br \/>\n\u2714 Buanderie avec laveuse + s\u00e9cheuse<\/p>\n<p>\u2605\u2605 CUISINE ET SALLE \u00c0 MANGER \u2605\u2605<br \/>\nLa cuisine enti\u00e8rement \u00e9quip\u00e9e comprend tous les appareils et commodit\u00e9s n\u00e9cessaires pour cuisiner comme \u00e0 la maison. Un coin repas et un bar offrent de nombreuses places assises pour vos invit\u00e9s, et des appareils de base tels qu&#039;un grille-pain, une cafeti\u00e8re, une friteuse sans huile, un cuiseur \u00e0 riz et un micro-ondes vous permettent de pr\u00e9parer facilement vos plats pr\u00e9f\u00e9r\u00e9s.<\/p>\n<p>\u2714 Cuisine enti\u00e8rement \u00e9quip\u00e9e avec appareils modernes<br \/>\n\u2714 Bar \u00e0 caf\u00e9 gratuit, machine \u00e0 caf\u00e9 Keurig incluse<br \/>\n\u2714 Batterie de cuisine et vaisselle de base<br \/>\n\u2714 Grande table \u00e0 manger pouvant accueillir 8 personnes<br \/>\n\u2714 Bar \u00e0 petit-d\u00e9jeuner avec si\u00e8ges de style bistro<br \/>\n\u2714 Armoires remplies d&#039;articles de cuisine essentiels<\/p>\n<p>\u2605\u2605 SALON \u2605\u2605<br \/>\nCe salon polyvalent peut servir \u00e0 regarder des films, \u00e0 se d\u00e9tendre, \u00e0 organiser une soir\u00e9e jeux en famille ou \u00e0 planifier vos aventures de la journ\u00e9e. Avec son mobilier confortable, sa d\u00e9coration th\u00e9matique, son acc\u00e8s direct \u00e0 la piscine ext\u00e9rieure et son impressionnant \u00e9cran plat au-dessus de la chemin\u00e9e, il deviendra vite le lieu de rencontre pr\u00e9f\u00e9r\u00e9 de votre famille.<\/p>\n<p>\u2714 T\u00e9l\u00e9vision intelligente \u00e0 \u00e9cran plat<br \/>\n\u2714 Canap\u00e9 confortable<br \/>\n\u2714 Fauteuil de massage inclinable confortable \u00e0 gravit\u00e9 z\u00e9ro<br \/>\n\u2714 Plantes d&#039;int\u00e9rieur feuillues + finitions design<br \/>\n\u2714 Console de jeu<br \/>\n\u2714 Lit de voyage et chaise haute Pack &#039;n Play<\/p>\n<p>\u2605\u2605 Salle de jeux d&#039;arcade \u2605\u2605<\/p>\n<p>\u2714 T\u00e9l\u00e9vision intelligente \u00e0 \u00e9cran plat<br \/>\n\u2714 Si\u00e8ges de cin\u00e9ma confortables<br \/>\n\u2714 Console de jeu<br \/>\n\u2714Jeux d&#039;arcade \u00e0 t\u00eate de dragon<br \/>\n\u2714Jeux de soci\u00e9t\u00e9<br \/>\n\u2714Chemin\u00e9e<br \/>\n\u2714Chaise tr\u00f4ne de fer Game of Thrones<\/p>\n<p>\u2605\u2605 Salle de cin\u00e9ma \u2605\u2605<\/p>\n<p>\u2714 Le Star Destroyer de Dark Vador dans la salle de cin\u00e9ma sur le th\u00e8me de Star Wars<br \/>\n\u2714 Son surround, si\u00e8ges inclinables moelleux<br \/>\n\u2714 Machine \u00e0 popcorn \u00e0 air (condiments inclus !).<\/p>\n<p>\u2605\u2605 ESPACE EXT\u00c9RIEUR \u2605\u2605<br \/>\nProfitez du beau temps de Floride. Et si vous avez envie d&#039;un bol d&#039;air frais sans quitter la maison, sortez simplement sur la v\u00e9randa avec moustiquaire au bord de la piscine\u00a0! Notre piscine d&#039;eau sal\u00e9e chauff\u00e9e et notre spa sont parfaits pour d\u00e9tendre et se ressourcer.<\/p>\n<p>G\u00c9N\u00c9RAL\u00a0: Les clients peuvent profiter d&#039;un acc\u00e8s priv\u00e9 \u00e0 toute la maison. Les s\u00e9jours de longue dur\u00e9e jusqu&#039;\u00e0 90 jours sont autoris\u00e9s.<\/p>\n<p>\u2739 L&#039;enregistrement automatique est facile via la serrure \u00e9lectronique de la porte d&#039;entr\u00e9e - un code personnalis\u00e9 vous sera fourni.<\/p>\n<p>\u2739 PARKING : Un parking gratuit sur place est disponible.<\/p>\n<p>\u2739 TRAVAIL \u00c0 DOMICILE : Une connexion Wi-Fi haut d\u00e9bit gratuite est disponible dans toute la maison, ainsi qu&#039;un espace de travail d\u00e9di\u00e9.<\/p>\n<p>\u2739 FAMILLE : Vous voyagez avec des petits ? Nous avons ce qu&#039;il vous faut avec quelques fournitures, dont un berceau de voyage Pack &#039;n Play.<\/p>\n<p>\u2739 ANIMAUX DE COMPAGNIE : Aucun animal de compagnie n&#039;est autoris\u00e9 \u00e0 l&#039;exception des animaux d&#039;assistance.<\/p>\n<p>\u2739 ACC\u00c8S COMMUNAUTAIRE : Vous aurez acc\u00e8s \u00e0 toutes les commodit\u00e9s communautaires du club house, y compris les courts de tennis, le centre de remise en forme, l&#039;aire de jeux et le terrain de volley-ball sabl\u00e9.<\/p>\n<p>N&#039;h\u00e9sitez pas \u00e0 nous contacter si vous avez des questions \u2013 nous sommes impatients de vous accueillir !<\/p>\n<p>Il est probable que vous ne nous voyiez pas pendant votre s\u00e9jour, ce qui vous assure plus d&#039;intimit\u00e9 et de confort. Cependant, nous sommes disponibles \u00e0 tout moment. Besoin de quoi que ce soit ou avez des questions\u00a0? Envoyez-nous un message via Airbnb et nous vous r\u00e9pondrons rapidement. L&#039;arriv\u00e9e s&#039;effectue de 15\u00a0h \u00e0 23\u00a0h. En cas d&#039;arriv\u00e9e tardive, veuillez nous pr\u00e9venir \u00e0 l&#039;avance. Le d\u00e9part s&#039;effectue \u00e0 10\u00a0h pr\u00e9cises.<\/p>\n<p>Cette maison de ville est situ\u00e9e \u00e0 proximit\u00e9 de nombreux restaurants, du centre commercial Walmart et de Publix.<\/p>\n<p>Disney World - 7,9 miles, 15 min en voiture<\/p>\n<p>Universal Studios \u2013 33,5 km, 38 minutes en voiture<\/p>\n<p>SeaWorld \u2013 27,2 km, 34 min en voiture<\/p>\n<p>Centre de congr\u00e8s du comt\u00e9 d&#039;Orange \u2013 30 km, 36 min en voiture<\/p>\n<p>LegoLand \u2013 47,1 km, 52 min en voiture<\/p>\n<p>\u2605\u2605 ACTIVIT\u00c9S\/ATTRACTIONS \u2605\u2605<br \/>\nIl existe de nombreuses activit\u00e9s agr\u00e9ables \u00e0 d\u00e9couvrir dans la r\u00e9gion de Davenport et notre maison de vacances constitue une rampe de lancement id\u00e9ale pour vos aventures. D\u00e9couvrez une gamme d\u2019options int\u00e9ressantes qui s\u2019offrent \u00e0 vous pendant votre s\u00e9jour.<\/p>\n<p>\u2714 TheatreWorks Florida - Th\u00e9\u00e2tre et Studio : D\u00e9couvrez les meilleures performances musicales th\u00e9\u00e2trales des locaux et des artistes de tout le pays.<br \/>\n\u2714 Disney Springs\u00a0: Les visiteurs appr\u00e9cient particuli\u00e8rement ce centre commercial qui propose une grande vari\u00e9t\u00e9 de restaurants, dont The Polite Pig, House of Blues et Cooks Fish and Chips, ainsi que de nombreuses boutiques vendant des produits et souvenirs Disney. Ils soulignent \u00e9galement l&#039;accueil chaleureux du personnel, la propret\u00e9 des installations et l&#039;ambiance anim\u00e9e avec concerts et animations.<br \/>\n\u2714 True Blue Winery : L&#039;atmosph\u00e8re conviviale du True Blue Winery avec le charme d&#039;une petite ville propose des vins faits maison prim\u00e9s, un bistrot, la cueillette de myrtilles, des mariages et des concerts.<br \/>\n\u2714 Providence Golf Club : Club de golf comprenant un parcours de 18 trous et des cours, ainsi qu&#039;une boutique professionnelle et un restaurant.<\/p>\n<p>Toutes ces activit\u00e9s et bien plus encore sont \u00e0 votre port\u00e9e lorsque vous r\u00e9servez avec nous !<\/p>\n<p>\u2605\u2606 R\u00e9servez d\u00e8s aujourd&#039;hui et laissez-nous prendre soin de vous \u00e0 Davenport, en Floride \u2606\u2605<\/p>\n<p>Transport:<\/p>\n<p>Des services Uber, Lyft, taxi et bus sont disponibles. Si vous voyagez depuis l&#039;a\u00e9roport international d&#039;Orlando, voici quelques informations utiles\u00a0:<\/p>\n<p>UBER \/ LYFT \/ TAXI<br \/>\nToutes les soci\u00e9t\u00e9s de covoiturage (telles que Uber, Lyft et \/taxi) peuvent prendre en charge les passagers sur le trottoir des arriv\u00e9es au : Terminal A (Niveau 2) et<br \/>\nau niveau 3 entre 21h00 et 2h00. Terminal B (Niveau 2) et<br \/>\nau niveau 3 entre 21h00 et 2h00. Terminal C (Niveau 6)<br \/>\nsitu\u00e9 \u00e0 l&#039;a\u00e9roport international d&#039;Orlando.<\/p>\n<p>BUS<br \/>\nLes passagers du SunRail peuvent d\u00e9sormais se rendre \u00e0 l&#039;a\u00e9roport international d&#039;Orlando<br \/>\nvia la liaison de bus vers la station SunRail de Sand Lake Road. SunRail<br \/>\nFonctionne du lundi au vendredi de 5h30 \u00e0 21h30. Le bus local Lynx<br \/>\nl&#039;arr\u00eat est situ\u00e9 au Terminal A, Niveau 1 (Transport terrestre), \u00e0<br \/>\nEspaces commerciaux Lane A38-A41.<\/p>\n<p>\u2605\u2606 R\u00e9servez d\u00e8s aujourd&#039;hui et laissez-nous prendre soin de vous \u00e0 Davenport ! \u2606\u2605<\/p>\n<p>\u2606\u2606 FAITS SAILLANTS \u2606\u2606<\/p>\n<p>\u2739 3 chambres spacieuses : 2 King, 1 full-over-full avec lits superpos\u00e9s gigognes jumeaux<br \/>\n\u2739 Canap\u00e9-lit queen-size gigogne<br \/>\n\u2739 Fauteuil de massage \u00e0 gravit\u00e9 z\u00e9ro<br \/>\n\u2739 4 salles de bains ; articles de toilette essentiels<br \/>\n\u2739 Cuisine compl\u00e8te avec appareils modernes<br \/>\n\u2739 Bar de petit-d\u00e9jeuner et salle \u00e0 manger formelle<br \/>\n\u2739Bouteille de vin offerte<br \/>\n\u2739 Espace de vie spacieux avec jeux de soci\u00e9t\u00e9 et consoles de jeux<br \/>\n\u2739 T\u00e9l\u00e9viseurs \u00e0 \u00e9cran plat \u00e9l\u00e9gants<br \/>\n\u2739 Wi-Fi haut d\u00e9bit et espace de travail d\u00e9di\u00e9<br \/>\n\u2739 Espace piscine priv\u00e9 avec mobilier d&#039;ext\u00e9rieur<br \/>\n\u2739 Barbecue (charbon de bois inclus)<br \/>\n\u2739 Laveuse + s\u00e9cheuse int\u00e9gr\u00e9es<br \/>\n\u2739 Acc\u00e8s au centre de remise en forme, au court de tennis, au terrain de volley-ball et \u00e0 l&#039;aire de jeux du complexe.<br \/>\n\u2739 Stationnement gratuit<br \/>\n\u2739 Possibilit\u00e9 de r\u00e9server des services sp\u00e9cialis\u00e9s tels qu&#039;un chef personnel, un massoth\u00e9rapeute, des services d&#039;entretien m\u00e9nager suppl\u00e9mentaires et une exp\u00e9rience de voiture de sport \u00e0 3 roues Polaris Slingshot<br \/>\n\u2739 Emplacement priv\u00e9 avec acc\u00e8s facile aux attractions locales, \u00e0 quelques minutes en voiture des restaurants et des \u00e9piceries<\/p>\n<p>Envie d&#039;en savoir plus ?<\/p>\n<p>\u2605 LOGEMENT SUPPL\u00c9MENTAIRE \u2605<br \/>\nVous voyagez en grand groupe ou vos dates pr\u00e9f\u00e9r\u00e9es sont d\u00e9j\u00e0 prises ? Vous serez heureux de savoir que nous proposons des maisons suppl\u00e9mentaires dans la r\u00e9gion. Veuillez parcourir notre profil d&#039;h\u00f4te pour la liste compl\u00e8te des magnifiques annonces.<\/p>\n<p>\u2605 NETTOYAGE ET ASSAINISSEMENT \u2605<br \/>\nLa sant\u00e9, la s\u00e9curit\u00e9 et le bien-\u00eatre de nos clients sont de la plus haute importance. C&#039;est pour cette raison que nous proc\u00e9dons \u00e0 un nettoyage minutieux apr\u00e8s chaque d\u00e9part.<\/p>\n<p>\u2739 Un code d&#039;acc\u00e8s sera envoy\u00e9 pour acc\u00e9der \u00e0 la porte de s\u00e9curit\u00e9 \u00e0 l&#039;entr\u00e9e.<\/p>\n<p>Piscine d&#039;eau sal\u00e9e chauff\u00e9e sur la propri\u00e9t\u00e9 <\/p>\n<p>\u2739 Des services suppl\u00e9mentaires VIP sont disponibles pour rendre votre voyage encore plus sp\u00e9cial\u00a0: chef personnel, massoth\u00e9rapeute, services d&#039;entretien m\u00e9nager suppl\u00e9mentaires ou exp\u00e9rience de voiture de sport \u00e0 3 roues Polaris Slingshot. Les r\u00e9servations doivent \u00eatre faites \u00e0 l&#039;avance. Des frais suppl\u00e9mentaires s&#039;appliquent. Veuillez nous contacter pour plus de d\u00e9tails.<\/p>\n<p>\u2739 Nous vous prions de bien vouloir maintenir la suite propre durant votre s\u00e9jour. Pour les r\u00e9servations effectu\u00e9es plus de deux semaines apr\u00e8s le d\u00e9part, un m\u00e9nage et\/ou une inspection seront effectu\u00e9s en milieu de s\u00e9jour.<\/p>\n<p>\u2739 Nous ne pouvons \u00eatre tenus responsables de la perte d&#039;effets personnels ou d&#039;objets de valeur. En acceptant cette r\u00e9servation, vous acceptez la responsabilit\u00e9 de votre groupe et de tous les invit\u00e9s que vous invitez dans les lieux et assumez le risque de tout pr\u00e9judice r\u00e9sultant de leur utilisation de cette propri\u00e9t\u00e9.<\/p>\n<p>\u2739 Un contrat de location est requis par la communaut\u00e9.<\/p>\n<p>\u2739Fumer\u00a0: il est interdit de fumer \u00e0 l&#039;int\u00e9rieur de la maison. Tout contrevenant sera passible d&#039;une amende de 1\u00a0TP4T100. Il est permis de fumer dans une zone d\u00e9sign\u00e9e \u00e0 l&#039;ext\u00e9rieur de la maison.<\/p>\n<p>**Important\u00a0:** Nous nous engageons \u00e0 prot\u00e9ger nos propri\u00e9t\u00e9s et \u00e0 respecter la r\u00e9glementation sur les locations de courte dur\u00e9e. C&#039;est pourquoi nous vous demanderons de compl\u00e9ter notre v\u00e9rification ind\u00e9pendante. (R\u00e9servation directe sur notre site web uniquement)  <\/p>\n<p>**Remarque importante\u00a0:** Avant que votre r\u00e9servation ne soit d\u00e9finitive, vous devrez v\u00e9rifier vos informations aupr\u00e8s de nous. Cette v\u00e9rification doit \u00eatre effectu\u00e9e dans les 24\u00a0heures suivant votre demande de r\u00e9servation. Vous serez contact\u00e9 par courriel et\/ou SMS pour effectuer la v\u00e9rification via notre syst\u00e8me Truvi ID. (Pour les r\u00e9servations effectu\u00e9es directement sur notre site web uniquement)<\/p>","protected":false},"excerpt":{"rendered":"<p>Step into a world of pure imagination in this epic, multiverse-themed retreat home just minutes from Orlando! With themes like Harry Potter, Game of Thrones, Star Wars, Black Panther, The Avengers, and Avatar, every room is a portal to a new universe. The home has everything you need. A heated Saltwater Pool, Hot Tub, Movie [&hellip;]<\/p>","protected":false},"author":8,"featured_media":200989,"parent":0,"menu_order":0,"template":"","listing_type":[533],"room_type":[],"amenities":[463,513,514,536,515,510,506,470,511,530,516,489,507,498,503,485,488,473,531,497,472,471,522,467,475,468,525,476,526,464,494,477,482,502,486,483,487,499,479,500,538,496,508,492,528,539,537,474,509,469,535,491,480,481,521,484,490,478,501,465,518,462],"facilities":[],"listing_countries":[459],"listing_states":[461],"listing_cities":[534],"listing_areas":[],"class_list":["post-198230","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_type-villa","listing_amenity-air-conditioning","listing_amenity-baking-sheet","listing_amenity-barbeque-utensils","listing_amenity-bidet","listing_amenity-blender","listing_amenity-board-games","listing_amenity-body-soap","listing_amenity-carbon-monoxide-detector","listing_amenity-ceiling-fan","listing_amenity-cleaning-products","listing_amenity-coffee","listing_amenity-coffee-tea-maker","listing_amenity-conditioner","listing_amenity-cooking-basics","listing_amenity-dining-table","listing_amenity-dishwasher","listing_amenity-electric-kettle","listing_amenity-essentials","listing_amenity-exercise-equipment","listing_amenity-extra-pillows-and-blankets","listing_amenity-fire-extinguisher","listing_amenity-first-aid-kit","listing_amenity-gym","listing_amenity-hair-dryer","listing_amenity-hangers","listing_amenity-heating","listing_amenity-hot-water","listing_amenity-iron","listing_amenity-jacuzzi","listing_amenity-kitchen","listing_amenity-kitchen-utensils","listing_amenity-laptop-friendly-workspace","listing_amenity-linens","listing_amenity-long-term-stays-allowed","listing_amenity-microwave","listing_amenity-outdoor-grill","listing_amenity-oven","listing_amenity-pack-n-play-travel-crib","listing_amenity-pets-allowed","listing_amenity-ping-pong-table","listing_amenity-pool-table","listing_amenity-private-entrance","listing_amenity-rain-shower","listing_amenity-refrigerator","listing_amenity-resort","listing_amenity-rice-maker","listing_amenity-room-darkening-shades","listing_amenity-shampoo","listing_amenity-shower-gel","listing_amenity-smoke-detector","listing_amenity-sound-system","listing_amenity-stove","listing_amenity-suitable-for-children","listing_amenity-suitable-for-infants","listing_amenity-swimming-pool","listing_amenity-toaster","listing_amenity-tub","listing_amenity-tv","listing_amenity-video-games","listing_amenity-washing-machine","listing_amenity-wine-glasses","listing_amenity-wireless","listing_country-united-states-of-america","listing_state-fl","listing_city-davenport"],"acf":[],"_links":{"self":[{"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listings\/198230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listings"}],"about":[{"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":28,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listings\/198230\/revisions"}],"predecessor-version":[{"id":203979,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listings\/198230\/revisions\/203979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/media\/200989"}],"wp:attachment":[{"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/media?parent=198230"}],"wp:term":[{"taxonomy":"listing_type","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listing_type?post=198230"},{"taxonomy":"room_type","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/room_type?post=198230"},{"taxonomy":"listing_amenity","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/amenities?post=198230"},{"taxonomy":"listing_facility","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/facilities?post=198230"},{"taxonomy":"listing_country","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listing_countries?post=198230"},{"taxonomy":"listing_state","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listing_states?post=198230"},{"taxonomy":"listing_city","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listing_cities?post=198230"},{"taxonomy":"listing_area","embeddable":true,"href":"https:\/\/floridahomeshares.com\/fr\/wp-json\/wp\/v2\/listing_areas?post=198230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}